{"id":37298,"date":"2025-02-23T11:36:34","date_gmt":"2025-02-23T10:36:34","guid":{"rendered":"http:\/\/litepack.ch\/?post_type=product&#038;p=37298"},"modified":"2026-05-21T07:58:08","modified_gmt":"2026-05-21T06:58:08","slug":"zpacks-potty-pack-mit-schaufel","status":"publish","type":"product","link":"https:\/\/litepack.ch\/en\/product\/zpacks-potty-pack-mit-schaufel\/","title":{"rendered":"Zpacks Potty Pack  mit Schaufel"},"content":{"rendered":"<p>Egal, ob du Gipfel erklimmst oder im Backcountry zeltest, das Potty Pack ist eine kompakte Aufbewahrungsm\u00f6glichkeit f\u00fcr Toilettenpapier, Feuchtt\u00fccher, Kulturbeutel und Kelle und kombiniert Funktionalit\u00e4t mit einem Hauch von abenteuerlichem Stil.<br \/>\nDas Potty Pack verf\u00fcgt \u00fcber ein spezielles Fach f\u00fcr die mitgelieferte ultraleichte Aluminiumkelle und sorgt daf\u00fcr, dass der Inhalt des Kits sauber und organisiert bleibt. Diese ultraleichte Rei\u00dfverschlusstasche besteht aus wasserabweisendem Material und einem robusten Design f\u00fcr Entdecker, die viel unterwegs sind. Sie sorgt daf\u00fcr, dass Ihre wichtigsten Utensilien trocken und einsatzbereit bleiben, egal wohin der Weg Sie f\u00fchrt.<\/p>\n<ul>\n<li>Das strapazierf\u00e4hige 100D Ripstop-Nylon mit einem Gewicht von 125 g\/m\u00b2 h\u00e4lt den Anforderungen von Langstrecken<a href=\"https:\/\/litepack.ch\/en\/pilgerreisen\/\" data-internallinksmanager029f6b8e52c=\"6\" title=\"Pilgerreisen\">wanderungen<\/a> stand.<\/li>\n<li>Perfekt f\u00fcr den Transport und die Organisation Ihrer Toilettenpapier, Wischt\u00fccher und andere Backcountry Badezimmer Artikel, die Sie in der N\u00e4he von Hand und sicher wollen.<\/li>\n<li>Der mitgelieferte <a href=\"\/en\/hersteller\/zpacks\/\" data-internallinksmanager029f6b8e52c=\"2\" title=\"Zpacks\">Zpacks<\/a> Ultralight Schaufel passt in eine integrierte H\u00fclle, um den Inhalt des Rucksacks sauber zu halten.<\/li>\n<li>Der Potty Pack ist wasserdicht. Bitte halten Sie Ihre TP in einem Zip-Lock.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Egal, ob du Gipfel erklimmst oder im Backcountry zeltest, das Potty Pack ist eine kompakte Aufbewahrungsm\u00f6glichkeit f\u00fcr Toilettenpapier, Feuchtt\u00fccher, Kulturbeutel<\/p>","protected":false},"featured_media":41765,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[220],"product_cat":[296,191],"product_tag":[],"class_list":["post-37298","product","type-product","status-publish","has-post-thumbnail","product_brand-zpacks","product_cat-weiteres-zubehoer","product_cat-zubehoer","pa_hersteller-zpacks","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/product\/37298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/comments?post=37298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/media\/41765"}],"wp:attachment":[{"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/media?parent=37298"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/product_brand?post=37298"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/product_cat?post=37298"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/litepack.ch\/en\/wp-json\/wp\/v2\/product_tag?post=37298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}